{"id":234569,"date":"2024-04-25T16:18:54","date_gmt":"2024-04-25T14:18:54","guid":{"rendered":"https:\/\/berneyassocies.com\/?page_id=234569"},"modified":"2024-08-25T17:50:39","modified_gmt":"2024-08-25T15:50:39","slug":"financial-advice-and-support","status":"publish","type":"page","link":"https:\/\/berneyassocies.com\/en\/entreprises-et-organisations\/conseil-en-gestion-et-services-externalises\/conseil-et-accompagnement-financier\/","title":{"rendered":"Financial advice and support"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#002856&Prime; custom_padding_tablet=\u00a0\u00bb1rem||1rem||true|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb1rem||1rem||true|false\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.0&Prime; _dynamic_attributes=\u00a0\u00bbcontent\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbTheW NYC Regular||||||||\u00a0\u00bb text_text_color=\u00a0\u00bbgcid-8e43273b-69bc-45d5-a817-07da9f1ce23e\u00a0\u00bb text_font_size=\u00a0\u00bb93px\u00a0\u00bb text_line_height=\u00a0\u00bb1.1em\u00a0\u00bb header_text_color=\u00a0\u00bbgcid-8e43273b-69bc-45d5-a817-07da9f1ce23e\u00a0\u00bb header_font_size=\u00a0\u00bb93px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb73px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb45px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb73px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb45px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-8e43273b-69bc-45d5-a817-07da9f1ce23e%22:%91%22header_text_color%22,%22text_text_color%22%93}\u00a0\u00bb]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF90aXRsZSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IiIsImFmdGVyIjoiIn19@[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_code module_class=\u00a0\u00bbbreadcrumb\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_module=\u00a0\u00bb233714&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_text_color=\u00a0\u00bb#002856&Prime; header_2_font_size=\u00a0\u00bb50px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.2em\u00a0\u00bb max_width=\u00a0\u00bb80%\u00a0\u00bb max_width_tablet=\u00a0\u00bb100%\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb25px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2><span style=\"font-weight: 400;\">Nos conseillers en gestion et comptabilit\u00e9 vous guident \u00e0 travers les d\u00e9fis complexes de la finance, pour <span style=\"color: #fb0346;\">prendre des d\u00e9cisions strat\u00e9giques<span style=\"color: #002856;\"> et<\/span> atteindre vos objectifs<\/span>.<\/span><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_text_color=\u00a0\u00bb#002856&Prime; header_2_font_size=\u00a0\u00bb50px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.2em\u00a0\u00bb header_3_text_color=\u00a0\u00bb#002856&Prime; header_3_font_size=\u00a0\u00bb30px\u00a0\u00bb max_width=\u00a0\u00bb80%\u00a0\u00bb max_width_tablet=\u00a0\u00bb100%\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb30px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Ce que nous vous proposons<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbAnalyse financi\u00e8re approfondie\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xe052;||divi||400&Prime; icon_color=\u00a0\u00bb#FB0346&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb image_icon_width=\u00a0\u00bb25px\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbHK Grotesk SemiBold||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#002856&Prime; header_font_size=\u00a0\u00bb24px\u00a0\u00bb body_text_color=\u00a0\u00bb#002856&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span data-metadata=\"&lt;!--(figmeta)eyJmaWxlS2V5IjoiTDRzQXZ3ckxQRllqMGVCb0E5dUFvVyIsInBhc3RlSUQiOjU4MzYzMzE2LCJkYXRhVHlwZSI6InNjZW5lIn0K(\/figmeta)--&gt;\"><\/span><span style=\"font-weight: 400;\">Nous commen\u00e7ons par une revue d\u00e9taill\u00e9e de vos finances pour identifier les zones d&rsquo;optimisation. Notre \u00e9quipe d&rsquo;experts examine chaque aspect de votre situation financi\u00e8re pour vous fournir des recommandations pr\u00e9cises, visant \u00e0 am\u00e9liorer votre performance financi\u00e8re.<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbPlanification financi\u00e8re strat\u00e9gique\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xe052;||divi||400&Prime; icon_color=\u00a0\u00bb#FB0346&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb image_icon_width=\u00a0\u00bb25px\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbHK Grotesk SemiBold||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#002856&Prime; header_font_size=\u00a0\u00bb24px\u00a0\u00bb body_text_color=\u00a0\u00bb#002856&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span data-metadata=\"&lt;!--(figmeta)eyJmaWxlS2V5IjoiTDRzQXZ3ckxQRllqMGVCb0E5dUFvVyIsInBhc3RlSUQiOjU4MzYzMzE2LCJkYXRhVHlwZSI6InNjZW5lIn0K(\/figmeta)--&gt;\"><\/span><span style=\"font-weight: 400;\">\u00c0 partir de notre analyse, nous \u00e9laborons une strat\u00e9gie financi\u00e8re sur mesure, align\u00e9e sur vos objectifs d&rsquo;entreprise. Qu&rsquo;il s&rsquo;agisse de la cr\u00e9ation d&rsquo;un budget pr\u00e9visionnel, de la mise en place d&rsquo;une organisation financi\u00e8re efficace ou de la planification de votre croissance, nous sommes l\u00e0 pour vous accompagner \u00e0 chaque \u00e9tape.<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbGestion de tr\u00e9sorerie\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xe052;||divi||400&Prime; icon_color=\u00a0\u00bb#FB0346&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb image_icon_width=\u00a0\u00bb25px\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbHK Grotesk SemiBold||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#002856&Prime; header_font_size=\u00a0\u00bb24px\u00a0\u00bb body_text_color=\u00a0\u00bb#002856&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span data-metadata=\"&lt;!--(figmeta)eyJmaWxlS2V5IjoiTDRzQXZ3ckxQRllqMGVCb0E5dUFvVyIsInBhc3RlSUQiOjU4MzYzMzE2LCJkYXRhVHlwZSI6InNjZW5lIn0K(\/figmeta)--&gt;\"><\/span><span style=\"font-weight: 400;\">\u00c0 partir de notre analyse, nous \u00e9laborons une strat\u00e9gie financi\u00e8re sur mesure, align\u00e9e sur vos objectifs d&rsquo;entreprise. Qu&rsquo;il s&rsquo;agisse de la cr\u00e9ation d&rsquo;un budget pr\u00e9visionnel, de la mise en place d&rsquo;une organisation financi\u00e8re efficace ou de la planification de votre croissance, nous sommes l\u00e0 pour vous accompagner \u00e0 chaque \u00e9tape.<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbGestion de tr\u00e9sorerie\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xe052;||divi||400&Prime; icon_color=\u00a0\u00bb#FB0346&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb image_icon_width=\u00a0\u00bb25px\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbHK Grotesk SemiBold||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#002856&Prime; header_font_size=\u00a0\u00bb24px\u00a0\u00bb body_text_color=\u00a0\u00bb#002856&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span data-metadata=\"&lt;!--(figmeta)eyJmaWxlS2V5IjoiTDRzQXZ3ckxQRllqMGVCb0E5dUFvVyIsInBhc3RlSUQiOjU4MzYzMzE2LCJkYXRhVHlwZSI6InNjZW5lIn0K(\/figmeta)--&gt;\"><\/span><span style=\"font-weight: 400;\">La tr\u00e9sorerie est le c\u0153ur de votre activit\u00e9\u00a0! Nous vous aidons \u00e0 optimiser votre gestion de tr\u00e9sorerie et \u00e0 am\u00e9liorer vos flux de tr\u00e9sorerie, assurant ainsi une stabilit\u00e9 financi\u00e8re durable pour votre entreprise.<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbInvestissement et Croissance\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xe052;||divi||400&Prime; icon_color=\u00a0\u00bb#FB0346&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb image_icon_width=\u00a0\u00bb25px\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbHK Grotesk SemiBold||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#002856&Prime; header_font_size=\u00a0\u00bb24px\u00a0\u00bb body_text_color=\u00a0\u00bb#002856&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span data-metadata=\"&lt;!--(figmeta)eyJmaWxlS2V5IjoiTDRzQXZ3ckxQRllqMGVCb0E5dUFvVyIsInBhc3RlSUQiOjU4MzYzMzE2LCJkYXRhVHlwZSI6InNjZW5lIn0K(\/figmeta)--&gt;\"><\/span><span style=\"font-weight: 400;\">Identifier les opportunit\u00e9s d&rsquo;investissement et d&rsquo;expansion est essentiel pour le d\u00e9veloppement de votre entreprise. Notre \u00e9quipe vous conseille sur les meilleures strat\u00e9gies d&rsquo;investissement, en tenant compte des risques et des avantages.<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb title=\u00a0\u00bbOptimisation fiscale\u00a0\u00bb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#xe052;||divi||400&Prime; icon_color=\u00a0\u00bb#FB0346&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb image_icon_width=\u00a0\u00bb25px\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bbHK Grotesk SemiBold||||||||\u00a0\u00bb header_text_color=\u00a0\u00bb#002856&Prime; header_font_size=\u00a0\u00bb24px\u00a0\u00bb body_text_color=\u00a0\u00bb#002856&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span style=\"font-weight: 400;\">Nous vous proposons des solutions d&rsquo;optimisation fiscale visant \u00e0 r\u00e9duire votre charge fiscale tout en restant en conformit\u00e9 avec les lois suisses.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Notre \u00e9quipe d&rsquo;experts en finance poss\u00e8de une connaissance approfondie des r\u00e9glementations financi\u00e8res et fiscales suisses, garantissant ainsi une conformit\u00e9 totale pour votre soci\u00e9t\u00e9.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nous \u00e9laborons un plan financier sur mesure qui vous permet de prendre des d\u00e9cisions \u00e9clair\u00e9es et de maximiser votre rentabilit\u00e9. <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width_tablet=\u00a0\u00bb100%\u00a0\u00bb width_phone=\u00a0\u00bb100%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb min_height_tablet=\u00a0\u00bb\u00a0\u00bb min_height_phone=\u00a0\u00bb\u00a0\u00bb min_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/berneyassocies.com\/wp-content\/uploads\/2024\/05\/berney-associes-fiduciaire-suisse-romande-cover-services-09-scaled.jpg\u00a0\u00bb title_text=\u00a0\u00bbberney-associes-fiduciaire-suisse-romande-cover-services-09&Prime; force_fullwidth=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||10vh||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||true|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; da_disable_devices=\u00a0\u00bboff|off|off\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime; da_is_popup=\u00a0\u00bboff\u00a0\u00bb da_exit_intent=\u00a0\u00bboff\u00a0\u00bb da_has_close=\u00a0\u00bbon\u00a0\u00bb da_alt_close=\u00a0\u00bboff\u00a0\u00bb da_dark_close=\u00a0\u00bboff\u00a0\u00bb da_not_modal=\u00a0\u00bbon\u00a0\u00bb da_is_singular=\u00a0\u00bboff\u00a0\u00bb da_with_loader=\u00a0\u00bboff\u00a0\u00bb da_has_shadow=\u00a0\u00bbon\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/berneyassocies.com\/wp-content\/uploads\/2024\/05\/berney-associes-fiduciaire-suisse-romande-service-CTA-02.jpg\u00a0\u00bb title_text=\u00a0\u00bbberney-associes-fiduciaire-suisse-romande-service-CTA-02&Prime; force_fullwidth=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb animation_direction=\u00a0\u00bbbottom\u00a0\u00bb animation_intensity_slide=\u00a0\u00bb3%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.23.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbTheW NYC Regular||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb30px\u00a0\u00bb text_line_height=\u00a0\u00bb1.3em\u00a0\u00bb width_tablet=\u00a0\u00bb\u00a0\u00bb width_phone=\u00a0\u00bb\u00a0\u00bb width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb26px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span style=\"font-weight: 400;\">Pour en savoir plus sur comment nous pouvons vous assister dans vos besoins, contactez-nous d\u00e8s aujourd&rsquo;hui. <\/span><\/p>\n<p>[\/et_pb_text][et_pb_code _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb global_module=\u00a0\u00bb239189&Prime; theme_builder_area=\u00a0\u00bbpost_content\u00a0\u00bb]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f239052-o1\" lang=\"fr-FR\" dir=\"ltr\" data-wpcf7-id=\"239052\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/234569#wpcf7-f239052-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulaire de contact\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"239052\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"fr_FR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f239052-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/><input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:239052,&quot;conditions&quot;:[{&quot;then_field&quot;:&quot;cv-pdf&quot;,&quot;and_rules&quot;:[{&quot;if_field&quot;:&quot;services&quot;,&quot;operator&quot;:&quot;equals&quot;,&quot;if_value&quot;:&quot;Postulation &amp; Offre spontan\\u00e9e&quot;}]}],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:true,&quot;repeater_remove_button&quot;:&quot;bottom&quot;}}\" \/>\n<\/fieldset>\n<div class=\"contact-form-services contact-form-CTA-select\">\n\t<div class=\"form-fields-info\">\n\t\t<div class=\"form-field field-text nom\">\n\t\t\t<p>Nom\n\t\t\t<\/p>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"nom\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"nom\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"form-field field-text prenom\">\n\t\t\t<p>Pr\u00e9nom\n\t\t\t<\/p>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"prenom\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"prenom\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"form-field field-text email\">\n\t\t\t<p>Email\n\t\t\t<\/p>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"form-field field-text telephone\">\n\t\t\t<p>T\u00e9l\u00e9phone\n\t\t\t<\/p>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-546\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel telephone-form\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-546\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"form-field field-text societe\">\n\t\t\t<p>Soci\u00e9t\u00e9 (facultatif)\n\t\t\t<\/p>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"societe\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"societe\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"form-field services\">\n\t\t\t<p>Par quel service \u00eates-vous int\u00e9ress\u00e9?\n\t\t\t<\/p>\n\t\t\t<div class=\"selected-services\">\n\t\t\t<\/div>\n\t\t\t<div class=\"dropdown\">\n\t\t\t\t<p><button type=\"button\" class=\"dropdown-toggle\">S\u00e9lectionnez les services<\/button>\n\t\t\t\t<\/p>\n\t\t\t\t<div class=\"dropdown-menu\">\n\t\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"services\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required dropdown-item\"><span class=\"wpcf7-list-item first\"><label><input type=\"checkbox\" name=\"services[]\" value=\"Audit\" \/><span class=\"wpcf7-list-item-label\">Audit<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"services[]\" value=\"Fiscalit\u00e9\" \/><span class=\"wpcf7-list-item-label\">Fiscalit\u00e9<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"services[]\" value=\"Conseil en gestion et services externalis\u00e9s\" \/><span class=\"wpcf7-list-item-label\">Conseil en gestion et services externalis\u00e9s<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"services[]\" value=\"Transactions d\u2019entreprise\" \/><span class=\"wpcf7-list-item-label\">Transactions d\u2019entreprise<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"services[]\" value=\"Conseil en entreprise et management\" \/><span class=\"wpcf7-list-item-label\">Conseil en entreprise et management<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"services[]\" value=\"Conseil juridique\" \/><span class=\"wpcf7-list-item-label\">Conseil juridique<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"services[]\" value=\"Startups &amp; Nouvelles activit\u00e9s\" \/><span class=\"wpcf7-list-item-label\">Startups &amp; Nouvelles activit\u00e9s<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"services[]\" value=\"Berney Insights\" \/><span class=\"wpcf7-list-item-label\">Berney Insights<\/span><\/label><\/span><span class=\"wpcf7-list-item last\"><label><input type=\"checkbox\" name=\"services[]\" value=\"Postulation &amp; Offre spontan\u00e9e\" \/><span class=\"wpcf7-list-item-label\">Postulation &amp; Offre spontan\u00e9e<\/span><\/label><\/span><\/span><\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"form-field succursale\">\n\t\t\t<p>Quelle succursale souhaitez-vous contacter?\n\t\t\t<\/p>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"succursale\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"succursale\"><option value=\"\">&#8212;Veuillez choisir une option&#8212;<\/option><option value=\"Gen\u00e8ve\">Gen\u00e8ve<\/option><option value=\"Lausanne\">Lausanne<\/option><option value=\"Fribourg\">Fribourg<\/option><option value=\"Nyon\">Nyon<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"form-field cv\">\n\t\t\t<div data-id=\"cv-pdf\" data-orig_data_id=\"cv-pdf\"  class=\"\" data-class=\"wpcf7cf_group\">\n\t\t\t\t<p>Transmettez votre CV au format PDF\n\t\t\t\t<\/p>\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"cv\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".pdf\" aria-invalid=\"false\" type=\"file\" name=\"cv\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-field field-text message\">\n\t\t<p>Votre message\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"3\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"message\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-field btn-submit\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envoyer\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><script><!-- [et_pb_line_break_holder] -->document.addEventListener('DOMContentLoaded', function () {<!-- [et_pb_line_break_holder] -->    var dropdownToggles = document.querySelectorAll('.dropdown-toggle');<!-- [et_pb_line_break_holder] -->    var dropdownMenus = document.querySelectorAll('.dropdown-menu');<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->    dropdownToggles.forEach(function(dropdownToggle, index) {<!-- [et_pb_line_break_holder] -->        var dropdownMenu = dropdownMenus[index];<!-- [et_pb_line_break_holder] -->        var selectedServicesContainer = dropdownMenu.closest('.form-field').querySelector('.selected-services');<!-- [et_pb_line_break_holder] -->        var form = dropdownMenu.closest('form');<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->        if (dropdownToggle && dropdownMenu) {<!-- [et_pb_line_break_holder] -->            dropdownToggle.addEventListener('click', function () {<!-- [et_pb_line_break_holder] -->                dropdownMenu.classList.toggle('active');<!-- [et_pb_line_break_holder] -->            });<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->            var checkboxes = dropdownMenu.querySelectorAll('input[type=\"checkbox\"]');<!-- [et_pb_line_break_holder] -->            if (checkboxes) {<!-- [et_pb_line_break_holder] -->                checkboxes.forEach(function (checkbox) {<!-- [et_pb_line_break_holder] -->                    checkbox.addEventListener('change', function () {<!-- [et_pb_line_break_holder] -->                        updateSelectedServices(checkboxes, selectedServicesContainer);<!-- [et_pb_line_break_holder] -->                    });<!-- [et_pb_line_break_holder] -->                });<!-- [et_pb_line_break_holder] -->            }<!-- [et_pb_line_break_holder] -->        }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->        \/\/ Ajout d'un \u00e9v\u00e9nement pour r\u00e9initialiser les services apr\u00e8s envoi du formulaire<!-- [et_pb_line_break_holder] -->        if (form) {<!-- [et_pb_line_break_holder] -->            form.addEventListener('submit', function () {<!-- [et_pb_line_break_holder] -->                \/\/ Attendre que l'envoi soit termin\u00e9 pour r\u00e9initialiser<!-- [et_pb_line_break_holder] -->                setTimeout(function () {<!-- [et_pb_line_break_holder] -->                    checkboxes.forEach(function (checkbox) {<!-- [et_pb_line_break_holder] -->                        checkbox.checked = false;<!-- [et_pb_line_break_holder] -->                    });<!-- [et_pb_line_break_holder] -->                    updateSelectedServices(checkboxes, selectedServicesContainer);<!-- [et_pb_line_break_holder] -->                }, 100);<!-- [et_pb_line_break_holder] -->            });<!-- [et_pb_line_break_holder] -->        }<!-- [et_pb_line_break_holder] -->    });<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->    function updateSelectedServices(checkboxes, selectedServicesContainer) {<!-- [et_pb_line_break_holder] -->        selectedServicesContainer.innerHTML = ''; \/\/ Clear previous selections<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->        checkboxes.forEach(function (checkbox) {<!-- [et_pb_line_break_holder] -->            if (checkbox.checked) {<!-- [et_pb_line_break_holder] -->                var service = document.createElement('div');<!-- [et_pb_line_break_holder] -->                service.className = 'selected-service';<!-- [et_pb_line_break_holder] -->                service.textContent = checkbox.nextSibling.textContent.trim();<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->                \/\/ Create the remove button<!-- [et_pb_line_break_holder] -->                var removeBtn = document.createElement('button');<!-- [et_pb_line_break_holder] -->                removeBtn.className = 'remove-service';<!-- [et_pb_line_break_holder] -->                removeBtn.textContent = '\u00d7';<!-- [et_pb_line_break_holder] -->                removeBtn.addEventListener('click', function () {<!-- [et_pb_line_break_holder] -->                    checkbox.checked = false;<!-- [et_pb_line_break_holder] -->                    updateSelectedServices(checkboxes, selectedServicesContainer);<!-- [et_pb_line_break_holder] -->                });<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->                service.appendChild(removeBtn);<!-- [et_pb_line_break_holder] -->                selectedServicesContainer.appendChild(service);<!-- [et_pb_line_break_holder] -->            }<!-- [et_pb_line_break_holder] -->        });<!-- [et_pb_line_break_holder] -->    }<!-- [et_pb_line_break_holder] -->});<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><\/script><!-- [et_pb_line_break_holder] -->[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos conseillers en gestion et comptabilit\u00e9 vous guident \u00e0 travers les d\u00e9fis complexes de la finance, pour prendre des d\u00e9cisions strat\u00e9giques et atteindre vos objectifs.Ce que nous vous proposonsNous commen\u00e7ons par une revue d\u00e9taill\u00e9e de vos finances pour identifier les zones d&rsquo;optimisation. Notre \u00e9quipe d&rsquo;experts examine chaque aspect de votre situation financi\u00e8re pour vous fournir [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":235929,"parent":29014,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-234569","page","type-page","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conseil et accompagnement financier - Berney Associ\u00e9s SA<\/title>\n<meta name=\"description\" content=\"Conseil et accompagnement financier Nos conseillers en gestion et comptabilit\u00e9 vous guident pour atteindre vos objectifs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/berneyassocies.com\/en\/companies-and-organisations\/management-consultancy-and-outsourced-services\/financial-advice-and-support\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conseil et accompagnement financier - Berney Associ\u00e9s SA\" \/>\n<meta property=\"og:description\" content=\"Conseil et accompagnement financier Nos conseillers en gestion et comptabilit\u00e9 vous guident pour atteindre vos objectifs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/berneyassocies.com\/en\/wp-json\/wp\/v2\/pages\/234569\" \/>\n<meta property=\"og:site_name\" content=\"Berney Associ\u00e9s SA\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-25T15:50:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/berneyassocies.com\/wp-content\/uploads\/2024\/05\/berney-associes-fiduciaire-suisse-romande-service-CTA-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1520\" \/>\n\t<meta property=\"og:image:height\" content=\"1074\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/berneyassocies.com\\\/entreprises-et-organisations\\\/conseil-en-gestion-et-services-externalises\\\/conseil-et-accompagnement-financier\\\/\",\"url\":\"https:\\\/\\\/berneyassocies.com\\\/entreprises-et-organisations\\\/conseil-en-gestion-et-services-externalises\\\/conseil-et-accompagnement-financier\\\/\",\"name\":\"Conseil et accompagnement financier - Berney Associ\u00e9s SA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/berneyassocies.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/berneyassocies.com\\\/entreprises-et-organisations\\\/conseil-en-gestion-et-services-externalises\\\/conseil-et-accompagnement-financier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/berneyassocies.com\\\/entreprises-et-organisations\\\/conseil-en-gestion-et-services-externalises\\\/conseil-et-accompagnement-financier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/berneyassocies.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/berney-associes-fiduciaire-suisse-romande-service-CTA-11.jpg\",\"datePublished\":\"2024-04-25T14:18:54+00:00\",\"dateModified\":\"2024-08-25T15:50:39+00:00\",\"description\":\"Conseil et accompagnement financier Nos conseillers en gestion et comptabilit\u00e9 vous guident pour atteindre vos objectifs.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/berneyassocies.com\\\/entreprises-et-organisations\\\/conseil-en-gestion-et-services-externalises\\\/conseil-et-accompagnement-financier\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/berneyassocies.com\\\/entreprises-et-organisations\\\/conseil-en-gestion-et-services-externalises\\\/conseil-et-accompagnement-financier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/berneyassocies.com\\\/entreprises-et-organisations\\\/conseil-en-gestion-et-services-externalises\\\/conseil-et-accompagnement-financier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/berneyassocies.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/berney-associes-fiduciaire-suisse-romande-service-CTA-11.jpg\",\"contentUrl\":\"https:\\\/\\\/berneyassocies.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/berney-associes-fiduciaire-suisse-romande-service-CTA-11.jpg\",\"width\":1520,\"height\":1074},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/berneyassocies.com\\\/entreprises-et-organisations\\\/conseil-en-gestion-et-services-externalises\\\/conseil-et-accompagnement-financier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Entreprises &#038; Organisations\",\"item\":\"https:\\\/\\\/berneyassocies.com\\\/entreprises-et-organisations\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseil en gestion et services externalis\u00e9s\",\"item\":\"https:\\\/\\\/berneyassocies.com\\\/entreprises-et-organisations\\\/conseil-en-gestion-et-services-externalises\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conseil et accompagnement financier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/berneyassocies.com\\\/#website\",\"url\":\"https:\\\/\\\/berneyassocies.com\\\/\",\"name\":\"Berney Associ\u00e9s SA\",\"description\":\"Votre fiduciaire en Suisse romande\",\"publisher\":{\"@id\":\"https:\\\/\\\/berneyassocies.com\\\/#organization\"},\"alternateName\":\"Votre fiduciaire en Suisse romande\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/berneyassocies.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/berneyassocies.com\\\/#organization\",\"name\":\"Berney Associ\u00e9s SA\",\"alternateName\":\"Votre fiduciaire en Suisse romande\",\"url\":\"https:\\\/\\\/berneyassocies.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/berneyassocies.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/berneyassocies.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Berney-Associes-Votre-Fiduciaire-en-Suisse-Romande.png\",\"contentUrl\":\"https:\\\/\\\/berneyassocies.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Berney-Associes-Votre-Fiduciaire-en-Suisse-Romande.png\",\"width\":1200,\"height\":628,\"caption\":\"Berney Associ\u00e9s SA\"},\"image\":{\"@id\":\"https:\\\/\\\/berneyassocies.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/berney-associ-s\\\/?originalSubdomain=fr\",\"https:\\\/\\\/www.instagram.com\\\/berneyassocies\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRPy3E8GsTbCeg0qWpCmkpw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conseil et accompagnement financier - Berney Associ\u00e9s SA","description":"Conseil et accompagnement financier Nos conseillers en gestion et comptabilit\u00e9 vous guident pour atteindre vos objectifs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/berneyassocies.com\/en\/companies-and-organisations\/management-consultancy-and-outsourced-services\/financial-advice-and-support\/","og_locale":"en_GB","og_type":"article","og_title":"Conseil et accompagnement financier - Berney Associ\u00e9s SA","og_description":"Conseil et accompagnement financier Nos conseillers en gestion et comptabilit\u00e9 vous guident pour atteindre vos objectifs.","og_url":"https:\/\/berneyassocies.com\/en\/wp-json\/wp\/v2\/pages\/234569","og_site_name":"Berney Associ\u00e9s SA","article_modified_time":"2024-08-25T15:50:39+00:00","og_image":[{"width":1520,"height":1074,"url":"https:\/\/berneyassocies.com\/wp-content\/uploads\/2024\/05\/berney-associes-fiduciaire-suisse-romande-service-CTA-11.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/berneyassocies.com\/entreprises-et-organisations\/conseil-en-gestion-et-services-externalises\/conseil-et-accompagnement-financier\/","url":"https:\/\/berneyassocies.com\/entreprises-et-organisations\/conseil-en-gestion-et-services-externalises\/conseil-et-accompagnement-financier\/","name":"Conseil et accompagnement financier - Berney Associ\u00e9s SA","isPartOf":{"@id":"https:\/\/berneyassocies.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/berneyassocies.com\/entreprises-et-organisations\/conseil-en-gestion-et-services-externalises\/conseil-et-accompagnement-financier\/#primaryimage"},"image":{"@id":"https:\/\/berneyassocies.com\/entreprises-et-organisations\/conseil-en-gestion-et-services-externalises\/conseil-et-accompagnement-financier\/#primaryimage"},"thumbnailUrl":"https:\/\/berneyassocies.com\/wp-content\/uploads\/2024\/05\/berney-associes-fiduciaire-suisse-romande-service-CTA-11.jpg","datePublished":"2024-04-25T14:18:54+00:00","dateModified":"2024-08-25T15:50:39+00:00","description":"Conseil et accompagnement financier Nos conseillers en gestion et comptabilit\u00e9 vous guident pour atteindre vos objectifs.","breadcrumb":{"@id":"https:\/\/berneyassocies.com\/entreprises-et-organisations\/conseil-en-gestion-et-services-externalises\/conseil-et-accompagnement-financier\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/berneyassocies.com\/entreprises-et-organisations\/conseil-en-gestion-et-services-externalises\/conseil-et-accompagnement-financier\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/berneyassocies.com\/entreprises-et-organisations\/conseil-en-gestion-et-services-externalises\/conseil-et-accompagnement-financier\/#primaryimage","url":"https:\/\/berneyassocies.com\/wp-content\/uploads\/2024\/05\/berney-associes-fiduciaire-suisse-romande-service-CTA-11.jpg","contentUrl":"https:\/\/berneyassocies.com\/wp-content\/uploads\/2024\/05\/berney-associes-fiduciaire-suisse-romande-service-CTA-11.jpg","width":1520,"height":1074},{"@type":"BreadcrumbList","@id":"https:\/\/berneyassocies.com\/entreprises-et-organisations\/conseil-en-gestion-et-services-externalises\/conseil-et-accompagnement-financier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Entreprises &#038; Organisations","item":"https:\/\/berneyassocies.com\/entreprises-et-organisations\/"},{"@type":"ListItem","position":2,"name":"Conseil en gestion et services externalis\u00e9s","item":"https:\/\/berneyassocies.com\/entreprises-et-organisations\/conseil-en-gestion-et-services-externalises\/"},{"@type":"ListItem","position":3,"name":"Conseil et accompagnement financier"}]},{"@type":"WebSite","@id":"https:\/\/berneyassocies.com\/#website","url":"https:\/\/berneyassocies.com\/","name":"Berney Associ\u00e9s SA","description":"Your trust company in French-speaking Switzerland","publisher":{"@id":"https:\/\/berneyassocies.com\/#organization"},"alternateName":"Votre fiduciaire en Suisse romande","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/berneyassocies.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/berneyassocies.com\/#organization","name":"Berney Associ\u00e9s SA","alternateName":"Votre fiduciaire en Suisse romande","url":"https:\/\/berneyassocies.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/berneyassocies.com\/#\/schema\/logo\/image\/","url":"https:\/\/berneyassocies.com\/wp-content\/uploads\/2025\/05\/Berney-Associes-Votre-Fiduciaire-en-Suisse-Romande.png","contentUrl":"https:\/\/berneyassocies.com\/wp-content\/uploads\/2025\/05\/Berney-Associes-Votre-Fiduciaire-en-Suisse-Romande.png","width":1200,"height":628,"caption":"Berney Associ\u00e9s SA"},"image":{"@id":"https:\/\/berneyassocies.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/berney-associ-s\/?originalSubdomain=fr","https:\/\/www.instagram.com\/berneyassocies\/","https:\/\/www.youtube.com\/channel\/UCRPy3E8GsTbCeg0qWpCmkpw"]}]}},"_links":{"self":[{"href":"https:\/\/berneyassocies.com\/en\/wp-json\/wp\/v2\/pages\/234569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berneyassocies.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/berneyassocies.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/berneyassocies.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/berneyassocies.com\/en\/wp-json\/wp\/v2\/comments?post=234569"}],"version-history":[{"count":18,"href":"https:\/\/berneyassocies.com\/en\/wp-json\/wp\/v2\/pages\/234569\/revisions"}],"predecessor-version":[{"id":239350,"href":"https:\/\/berneyassocies.com\/en\/wp-json\/wp\/v2\/pages\/234569\/revisions\/239350"}],"up":[{"embeddable":true,"href":"https:\/\/berneyassocies.com\/en\/wp-json\/wp\/v2\/pages\/29014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berneyassocies.com\/en\/wp-json\/wp\/v2\/media\/235929"}],"wp:attachment":[{"href":"https:\/\/berneyassocies.com\/en\/wp-json\/wp\/v2\/media?parent=234569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}